{"id":29455,"date":"2026-03-17T10:08:55","date_gmt":"2026-03-17T03:08:55","guid":{"rendered":"https:\/\/stei.itb.ac.id\/redesign\/?post_type=tribe_events&#038;p=29455"},"modified":"2026-03-17T10:08:55","modified_gmt":"2026-03-17T03:08:55","slug":"pendaftaran-semester-pendek-2025-2026","status":"publish","type":"tribe_events","link":"https:\/\/stei.itb.ac.id\/redesign\/event\/pendaftaran-semester-pendek-2025-2026\/","title":{"rendered":"Pendaftaran Semester Pendek 2025\/2026"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-29455","tribe_events","type-tribe_events","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/tribe_events\/29455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/tribe_events\/29455\/revisions"}],"predecessor-version":[{"id":29456,"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/tribe_events\/29455\/revisions\/29456"}],"wp:attachment":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/media?parent=29455"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/tags?post=29455"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/tribe_events_cat?post=29455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}