{"id":55,"count":1,"description":"","link":"https:\/\/stei.itb.ac.id\/redesign\/tag\/android\/","name":"android","slug":"android","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/tags\/55","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/posts?tags=55"},{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/tribe_events?tags=55"},{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/tec_calendar_embed?tags=55"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}