{"id":525,"count":1,"description":"","link":"https:\/\/stei.itb.ac.id\/redesign\/tag\/stei-itb-en\/","name":"stei itb","slug":"stei-itb-en","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/tags\/525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/posts?tags=525"},{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/tribe_events?tags=525"},{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/tec_calendar_embed?tags=525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}