{"id":38,"count":4,"description":"","link":"https:\/\/stei.itb.ac.id\/redesign\/tag\/teknik-komputer\/","name":"teknik komputer","slug":"teknik-komputer","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/tags\/38","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/posts?tags=38"},{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/tribe_events?tags=38"},{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/tec_calendar_embed?tags=38"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}