{"id":15276,"date":"2021-10-08T21:53:30","date_gmt":"2021-10-08T14:53:30","guid":{"rendered":"https:\/\/stei.itb.ac.id\/redesign\/?page_id=15276"},"modified":"2021-10-09T01:43:20","modified_gmt":"2021-10-08T18:43:20","slug":"irma-zakia","status":"publish","type":"page","link":"https:\/\/stei.itb.ac.id\/redesign\/blog-dosen\/irma-zakia\/","title":{"rendered":"Irma Zakia"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":766,"featured_media":0,"parent":12671,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-15276","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/pages\/15276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/users\/766"}],"replies":[{"embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/comments?post=15276"}],"version-history":[{"count":0,"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/pages\/15276\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/pages\/12671"}],"wp:attachment":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/media?parent=15276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}