{"id":14755,"date":"2021-10-04T23:14:12","date_gmt":"2021-10-04T16:14:12","guid":{"rendered":"https:\/\/stei.itb.ac.id\/redesign\/?page_id=14755"},"modified":"2021-10-08T23:41:39","modified_gmt":"2021-10-08T16:41:39","slug":"bambang-anggoro-soedjarno-p","status":"publish","type":"page","link":"https:\/\/stei.itb.ac.id\/redesign\/blog-dosen\/bambang-anggoro-soedjarno-p\/","title":{"rendered":"Bambang Anggoro Soedjarno P."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":723,"featured_media":0,"parent":12671,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-14755","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/pages\/14755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/users\/723"}],"replies":[{"embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/comments?post=14755"}],"version-history":[{"count":0,"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/pages\/14755\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/pages\/12671"}],"wp:attachment":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/media?parent=14755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}