{"id":14610,"date":"2021-10-04T07:44:09","date_gmt":"2021-10-04T00:44:09","guid":{"rendered":"https:\/\/stei.itb.ac.id\/redesign\/?page_id=14610"},"modified":"2021-10-08T23:29:43","modified_gmt":"2021-10-08T16:29:43","slug":"albarda-publikasi","status":"publish","type":"page","link":"https:\/\/stei.itb.ac.id\/redesign\/blog-dosen\/albarda\/albarda-publikasi\/","title":{"rendered":"Albarda Publikasi"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":707,"featured_media":0,"parent":14608,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-14610","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/pages\/14610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/users\/707"}],"replies":[{"embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/comments?post=14610"}],"version-history":[{"count":0,"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/pages\/14610\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/pages\/14608"}],"wp:attachment":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/media?parent=14610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}