{"id":13149,"date":"2021-06-25T22:35:33","date_gmt":"2021-06-25T15:35:33","guid":{"rendered":"https:\/\/stei.itb.ac.id\/redesign\/?page_id=13149"},"modified":"2021-06-25T22:37:08","modified_gmt":"2021-06-25T15:37:08","slug":"dessi-puji-lestari","status":"publish","type":"page","link":"https:\/\/stei.itb.ac.id\/redesign\/blog-dosen\/dessi-puji-lestari\/","title":{"rendered":"Dessi Puji Lestari"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":735,"featured_media":0,"parent":12671,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-13149","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/pages\/13149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/users\/735"}],"replies":[{"embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/comments?post=13149"}],"version-history":[{"count":0,"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/pages\/13149\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/pages\/12671"}],"wp:attachment":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/media?parent=13149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}