{"id":13038,"date":"2021-06-24T19:42:23","date_gmt":"2021-06-24T12:42:23","guid":{"rendered":"https:\/\/stei.itb.ac.id\/redesign\/?page_id=13038"},"modified":"2021-06-24T19:42:23","modified_gmt":"2021-06-24T12:42:23","slug":"benhard-sitohang","status":"publish","type":"page","link":"https:\/\/stei.itb.ac.id\/redesign\/blog-dosen\/benhard-sitohang\/","title":{"rendered":"Benhard Sitohang"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":726,"featured_media":0,"parent":12671,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-13038","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/pages\/13038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/users\/726"}],"replies":[{"embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/comments?post=13038"}],"version-history":[{"count":0,"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/pages\/13038\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/pages\/12671"}],"wp:attachment":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/media?parent=13038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}