{"id":270,"count":706,"description":"","link":"https:\/\/stei.itb.ac.id\/redesign\/category\/berita\/","name":"Berita","slug":"berita","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/categories\/270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/posts?categories=270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}