{"id":1866,"count":1,"description":"","link":"https:\/\/stei.itb.ac.id\/redesign\/category\/research-group\/computer-engineering-research-group\/","name":"Computer Engineering Research Group","slug":"computer-engineering-research-group","taxonomy":"category","parent":1850,"meta":[],"_links":{"self":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/categories\/1866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/categories\/1850"}],"wp:post_type":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/wp-json\/wp\/v2\/posts?categories=1866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}