{"id":1194,"count":17,"description":"","link":"https:\/\/stei.itb.ac.id\/redesign\/en\/events\/category\/acara-institusi\/","name":"Acara Institusi","slug":"acara-institusi","taxonomy":"tribe_events_cat","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/tribe_events_cat\/1194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/tribe_events_cat"}],"about":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/taxonomies\/tribe_events_cat"}],"wp:post_type":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/tribe_events?tribe_events_cat=1194"},{"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/tec_calendar_embed?tribe_events_cat=1194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}