{"id":22142,"date":"2024-09-21T14:04:39","date_gmt":"2024-09-21T07:04:39","guid":{"rendered":"https:\/\/stei.itb.ac.id\/redesign\/?post_type=tribe_events&#038;p=22142"},"modified":"2024-09-21T14:04:39","modified_gmt":"2024-09-21T07:04:39","slug":"general-lecture-soft-robots-with-origami-self-folding-technology","status":"publish","type":"tribe_events","link":"https:\/\/stei.itb.ac.id\/redesign\/en\/event\/general-lecture-soft-robots-with-origami-self-folding-technology\/","title":{"rendered":"General Lecture : Soft Robots with Origami Self-Folding Technology"},"content":{"rendered":"<p>\ud83c\udf1f Invitation to a General Lecture \ud83c\udf1f<\/p>\n<p>Title: Soft Robots with Origami Self-Folding Technology<br \/>\nSpeaker: Dr. Hiroki Shigemune, Shibaura Institute of Technology, Japan<br \/>\nDate: Monday, 23 September 2-24<br \/>\nTime: 3:00 PM<br \/>\nVenue: Room TVST A<\/p>\n<p>Join us for an insightful lecture where Dr. Dr. Hiroki Shigemune from Shibaura Institute of Technology, Japan will explore cutting-edge innovations in soft robotics, specifically focusing on the fascinating world of origami self-folding technology.<\/p>\n<p>Don&#8217;t miss this opportunity to delve into the future of robotics and design!<\/p>\n<p>We look forward to seeing\u00a0you\u00a0there!<\/p>","protected":false},"excerpt":{"rendered":"<p>\ud83c\udf1f Invitation to a General Lecture \ud83c\udf1f Title: Soft Robots with Origami Self-Folding Technology Speaker: Dr. Hiroki Shigemune, Shibaura Institute of Technology, Japan Date: Monday, 23 September 2-24 Time: 3:00 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":22143,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[2007,381,2008,65,2006,383],"tribe_events_cat":[1194],"class_list":["post-22142","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-general-lecture","tag-itb","tag-lecture","tag-stei-2","tag-stei-hebat","tag-stei-itb","tribe_events_cat-acara-institusi","cat_acara-institusi"],"_links":{"self":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/tribe_events\/22142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/tribe_events\/22142\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/media\/22143"}],"wp:attachment":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/media?parent=22142"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/tags?post=22142"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=22142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}