{"id":12201,"date":"2021-05-25T15:18:05","date_gmt":"2021-05-25T08:18:05","guid":{"rendered":"https:\/\/stei.itb.ac.id\/redesign\/?p=12201"},"modified":"2021-05-25T16:17:35","modified_gmt":"2021-05-25T09:17:35","slug":"daftar-nama-usulan-adjunct-professor-stei-itb","status":"publish","type":"post","link":"https:\/\/stei.itb.ac.id\/redesign\/en\/daftar-nama-usulan-adjunct-professor-stei-itb\/","title":{"rendered":"Daftar Nama Usulan Adjunct Professor STEI ITB"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":12204,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1069,1230,1216,1222],"tags":[],"class_list":["post-12201","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-edaran","category-edaran-2","category-informasi","category-informasi-internal"],"_links":{"self":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/posts\/12201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/comments?post=12201"}],"version-history":[{"count":0,"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/posts\/12201\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/media\/12204"}],"wp:attachment":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/media?parent=12201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/categories?post=12201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/tags?post=12201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}