{"id":16217,"date":"2021-10-13T16:20:25","date_gmt":"2021-10-13T09:20:25","guid":{"rendered":"https:\/\/stei.itb.ac.id\/redesign\/?page_id=16217"},"modified":"2021-10-13T16:20:25","modified_gmt":"2021-10-13T09:20:25","slug":"syarif-hidayat","status":"publish","type":"page","link":"https:\/\/stei.itb.ac.id\/redesign\/en\/blog-dosen\/syarif-hidayat\/","title":{"rendered":"Syarif Hidayat"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":809,"featured_media":0,"parent":12671,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-16217","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/pages\/16217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/users\/809"}],"replies":[{"embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/comments?post=16217"}],"version-history":[{"count":0,"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/pages\/16217\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/pages\/12671"}],"wp:attachment":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/media?parent=16217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}