{"id":15251,"date":"2021-10-08T21:35:13","date_gmt":"2021-10-08T14:35:13","guid":{"rendered":"https:\/\/stei.itb.ac.id\/redesign\/?page_id=15251"},"modified":"2021-10-09T01:40:12","modified_gmt":"2021-10-08T18:40:12","slug":"hilwadi-hindersah","status":"publish","type":"page","link":"https:\/\/stei.itb.ac.id\/redesign\/en\/blog-dosen\/hilwadi-hindersah\/","title":{"rendered":"Hilwadi Hindersah"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":763,"featured_media":0,"parent":12671,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-15251","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/pages\/15251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/users\/763"}],"replies":[{"embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/comments?post=15251"}],"version-history":[{"count":0,"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/pages\/15251\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/pages\/12671"}],"wp:attachment":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/media?parent=15251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}