{"id":14480,"date":"2021-09-26T23:13:59","date_gmt":"2021-09-26T16:13:59","guid":{"rendered":"https:\/\/stei.itb.ac.id\/redesign\/?page_id=14480"},"modified":"2021-10-08T23:23:14","modified_gmt":"2021-10-08T16:23:14","slug":"adi-mulyanto","status":"publish","type":"page","link":"https:\/\/stei.itb.ac.id\/redesign\/en\/blog-dosen\/adi-mulyanto\/","title":{"rendered":"Adi Mulyanto"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":699,"featured_media":0,"parent":12671,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-14480","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/pages\/14480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/users\/699"}],"replies":[{"embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/comments?post=14480"}],"version-history":[{"count":0,"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/pages\/14480\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/pages\/12671"}],"wp:attachment":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/media?parent=14480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}