{"id":13179,"date":"2021-06-26T13:18:53","date_gmt":"2021-06-26T06:18:53","guid":{"rendered":"https:\/\/stei.itb.ac.id\/redesign\/?page_id=13179"},"modified":"2021-06-26T13:18:53","modified_gmt":"2021-06-26T06:18:53","slug":"agung-blog-post","status":"publish","type":"page","link":"https:\/\/stei.itb.ac.id\/redesign\/en\/blog-dosen\/agung-wahyu-setiawan\/agung-blog-post\/","title":{"rendered":"Agung Blog Post"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":703,"featured_media":0,"parent":13178,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-13179","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/pages\/13179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/users\/703"}],"replies":[{"embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/comments?post=13179"}],"version-history":[{"count":0,"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/pages\/13179\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/pages\/13178"}],"wp:attachment":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/media?parent=13179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}