{"id":1886,"count":1,"description":"","link":"https:\/\/stei.itb.ac.id\/redesign\/en\/category\/undergraduate-program\/undergraduate-program-of-biomedical-engineering\/","name":"Undergraduate Program of Biomedical Engineering","slug":"undergraduate-program-of-biomedical-engineering","taxonomy":"category","parent":1884,"meta":[],"_links":{"self":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/categories\/1886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/categories\/1884"}],"wp:post_type":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/posts?categories=1886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}