{"id":1715,"count":2,"description":"","link":"https:\/\/stei.itb.ac.id\/redesign\/en\/category\/blogpost-dosen\/syarif-hidayat\/","name":"Syarif Hidayat","slug":"syarif-hidayat","taxonomy":"category","parent":1303,"meta":[],"_links":{"self":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/categories\/1715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/categories\/1303"}],"wp:post_type":[{"href":"https:\/\/stei.itb.ac.id\/redesign\/en\/wp-json\/wp\/v2\/posts?categories=1715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}